{"id":518,"date":"2019-06-18T19:07:43","date_gmt":"2019-06-18T19:07:43","guid":{"rendered":"https:\/\/cmiwp.isedd.net\/?page_id=518"},"modified":"2024-04-24T14:21:25","modified_gmt":"2024-04-24T14:21:25","slug":"durchlauferhitzer-fuer-reinstwasser-mi-rw-dex","status":"publish","type":"page","link":"https:\/\/cmiwp.isedd.net\/en\/durchlauferhitzer-fuer-reinstwasser-mi-rw-dex\/","title":{"rendered":"Instantaneous water heater for ultrapure water MI-RW-DEX-V2"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"518\" class=\"elementor elementor-518\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-728ab1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"728ab1c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f79add\" data-id=\"1f79add\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-824385d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"824385d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a32aa7f\" data-id=\"a32aa7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba30acb elementor-widget elementor-widget-text-editor\" data-id=\"ba30acb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong><a href=\"https:\/\/cmiwp.isedd.net\/en\/durchlauferhitzer-fuer-reinstwasser-mi-rw-isx\/\">Nicht mehr lieferbar! <\/a><\/strong><br \/><br \/><a href=\"https:\/\/cmiwp.isedd.net\/en\/durchlauferhitzer-fuer-reinstwasser-mi-rw-isx\/\"><strong>Nachfolgemodell ist der Typ MI-RW-ISX<\/strong><\/a><\/h2><h2>\u00a0<\/h2><h2>Heating completely demineralised water<\/h2><p>Der vollelektronisch geregelte Durchlauferhitzer mit<br \/>dynamischer Durchflussmengenregelung eignet sich perfekt f\u00fcr die<br \/>komfortable Bereitstellung von warmem<\/p><ul><li><p>Reinstwasser,<\/p><\/li><li><p>Deionised water \u2013 fully desalinated water<\/p><\/li><li><p>DI water \u2013 demineralised water<\/p><\/li><li><p>DEMI-Wasser,<\/p><\/li><li><p>Aqua valde purificata,<\/p><\/li><li><p>Deionat,<\/p><\/li><li><p>WFI &#8211; Water for injection,<\/p><\/li><li><p>HPW &#8211; Highly Purified Water<\/p><\/li><li><p>demineralised water or<\/p><\/li><li><p>fully desalinated water<\/p><\/li><\/ul><p>in your production environment.<\/p><p>Die Leistungsaufnahme wird elektronisch geregelt in Abh\u00e4ngigkeit von<br \/>Zulauftemperatur und Durchfluss, um die eingestellte Auslauftemperatur<br \/>bis zu 60\u00b0C stets gradgenau zu erreichen und konstant zu halten. Die<br \/>maximale Leistungsaufnahme (18\u201327 kW) ist bei der Installation<br \/>bestimmbar.<\/p><hr \/><h2>\u00a0<\/h2><h2>Highlights<\/h2><ul><li><p>Easy to operate<\/p><\/li><li><p>Easy to install<\/p><\/li><li><p>Automatic self-monitoring<\/p><\/li><li><p>Low operating costs (<b>L<\/b>ow <b>C<\/b>ost<br \/>of <b>O<\/b>wnership)<\/p><\/li><li><p>Anwendungs- und kundenspezifische Versionen m\u00f6glich (z.B.<br \/>andere Betriebsspannungen)<\/p><\/li><\/ul><hr \/><h2>\u00a0<\/h2><h2>Areas of application<\/h2><ul><li><p>Process water heating<\/p><\/li><li><p>Manufacture of optical storage media<\/p><\/li><li><p>Semiconductor production \u2013 Process water in the wafer area<\/p><\/li><li><p>Production processes in the field of photovoltaics \u2013 manufacturing<br \/>von Solarzellen<\/p><\/li><li><p>Medizintechnik, z.B. Dialyseanlagen<\/p><\/li><li><p>Printed circuit board cleaning systems<\/p><\/li><li><p>Lebensmittelverarbeitung &#8211; z.B. Kunstdarmherstellung oder<br \/>Reinigung von Flaschen- und Beh\u00e4ltern<\/p><\/li><li><p>Paper processing<\/p><\/li><li><p>Electroplating \u2013 e.g. replenishing evaporation losses without temperature fluctuations<\/p><\/li><li><p>Water treatment<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6937a92\" data-id=\"6937a92\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-337ee80 elementor-widget elementor-widget-image\" data-id=\"337ee80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"730\" height=\"960\" src=\"https:\/\/cmiwp.isedd.net\/wp-content\/uploads\/2019\/06\/MI-RW-DEX_I-779x1024.jpg\" class=\"attachment-large size-large wp-image-552\" alt=\"Durchlauferhitzer f\u00fcr Reinstwasser\" srcset=\"https:\/\/cmiwp.isedd.net\/wp-content\/uploads\/2019\/06\/MI-RW-DEX_I-779x1024.jpg 779w, https:\/\/cmiwp.isedd.net\/wp-content\/uploads\/2019\/06\/MI-RW-DEX_I-228x300.jpg 228w, https:\/\/cmiwp.isedd.net\/wp-content\/uploads\/2019\/06\/MI-RW-DEX_I-768x1010.jpg 768w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa0e0b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5aa0e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67c5b91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67c5b91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87dc15c\" data-id=\"87dc15c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-908f2a7 elementor-widget elementor-widget-heading\" data-id=\"908f2a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Further information:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d105ea8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d105ea8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc947dc\" data-id=\"dc947dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbe8a53 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"cbe8a53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2131\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2131\" aria-expanded=\"false\">Technical specifications<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2132\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2132\" aria-expanded=\"false\">Data sheets<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2131\" aria-expanded=\"false\">Technical specifications<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2131\" tabindex=\"0\" hidden=\"false\"><table style=\"text-align: left; width: 100%;\" border=\"1\" cellspacing=\"2\" cellpadding=\"2\"><tbody><tr><td>Water volume<\/td><td>0,4l<\/td><\/tr><tr><td>Start-up flow rate<\/td><td>2l\/min (Standard &#8211; andere auf Anfrage)<\/td><\/tr><tr><td>Water connection<\/td><td>Quetschverschraubung \u00d810mm<\/td><\/tr><tr><td>Inlet temperature<\/td><td>+5\u00b0C&#8230;+70\u00b0C<\/td><\/tr><tr><td>Adjustable outlet temperature<\/td><td>+5\u00b0C&#8230;+70\u00b0C (Standard &#8211; andere auf Anfrage)<\/td><\/tr><tr><td>Weight<\/td><td>ca. 3,7kg (mit Wasserf\u00fcllung)<\/td><\/tr><tr><td>Dimensions<\/td><td>ca. 466x231x97mm<\/td><\/tr><tr><td>Supply voltage<\/td><td>400Vac \u2013 3-phase \u2013 PE \u2013 50Hz\/60Hz (standard \u2013 others on request)<\/td><\/tr><tr><td>Rated power<\/td><td>18&#8230;27kW (in 3kW-Stufen bei Installation festlegbar)<\/td><\/tr><\/tbody><\/table><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2132\" aria-expanded=\"false\">Data sheets<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2132\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2132\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/cmiwp.isedd.net\/wp-content\/uploads\/2019\/06\/Datenblatt-Heater-MI-RW-DEX-V2-Rev1.00.pdf\">Datenblatt MI-RW-DEX-V2<\/a><\/li><li><a href=\"https:\/\/cmiwp.isedd.net\/wp-content\/uploads\/2019\/06\/Datenblatt-RWDEX-Zubeh\u00f6r-Rev0.11.pdf\">Accessories\/fittings for instantaneous water heaters<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nicht mehr lieferbar! Nachfolgemodell ist der Typ MI-RW-ISX \u00a0 Erhitzen von vollentsalztem Wasser Der vollelektronisch geregelte Durchlauferhitzer mitdynamischer Durchflussmengenregelung eignet sich perfekt f\u00fcr diekomfortable Bereitstellung von warmem Reinstwasser, VE-Wasser &#8211; vollentsalztem Wasser DI-Wasser &#8211; demineralisiertem Wasser DEMI-Wasser, Aqua valde purificata, <a href=\"https:\/\/cmiwp.isedd.net\/en\/durchlauferhitzer-fuer-reinstwasser-mi-rw-dex\/\"> Read more&#8230;<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-518","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/pages\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":15,"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/pages\/518\/revisions"}],"predecessor-version":[{"id":3825,"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/pages\/518\/revisions\/3825"}],"wp:attachment":[{"href":"https:\/\/cmiwp.isedd.net\/en\/wp-json\/wp\/v2\/media?parent=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}